{"id":1291,"date":"2025-03-03T14:29:48","date_gmt":"2025-03-03T14:29:48","guid":{"rendered":"https:\/\/parc6456.novae.website\/alojamiento\/"},"modified":"2025-10-14T09:31:02","modified_gmt":"2025-10-14T09:31:02","slug":"alojamiento","status":"publish","type":"page","link":"https:\/\/www.hotel-parc-beaumont.com\/es\/alojamiento\/","title":{"rendered":"Alojamiento"},"content":{"rendered":"[vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb1636&#8243; bg_position=\u00bbcenter bottom\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb video_bg=\u00bbuse_video\u00bb enable_video_color_overlay=\u00bbtrue\u00bb video_overlay_color=\u00bbrgba(0,0,0,0.25)\u00bb video_mp4=\u00bbhttps:\/\/www.hotel-parc-beaumont.com\/wp-content\/uploads\/2025\/10\/VIDEO_BEAUMONT_1_MUTE_Alt_3480.mp4&#8243; video_image=\u00bb1636&#8243; background_video_loading=\u00bblazy-load\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb35%\u00bb bottom_padding=\u00bb2%\u00bb left_padding_desktop=\u00bb60&#8243; constrain_group_2=\u00bbyes\u00bb right_padding_desktop=\u00bb60&#8243; left_padding_phone=\u00bb18px\u00bb constrain_group_6=\u00bbyes\u00bb right_padding_phone=\u00bb18px\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbhpb_home\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bbrgba(0,0,0,0.01)\u00bb color_overlay_2=\u00bbrgba(0,0,0,0.4)\u00bb overlay_strength=\u00bb1&#8243; gradient_direction=\u00bbtop_to_bottom\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb parallax_bg=\u00bbtrue\u00bb parallax_bg_speed=\u00bbmedium\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_margin=\u00bb60px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbscroll_pos_advanced\u00bb animation_trigger_offset=\u00bb60.00,90.00&#8243; animation_end_translate_y=\u00bb-100&#8243; animation_end_opacity=\u00bb0&#8243; bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb animation_adv_start_end=\u00bbend\u00bb][vc_column_text css_animation=\u00bbfadeInUp\u00bb css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb el_class=\u00bbvector_title v_alt\u00bb]<span class=\"top_line\">Alojamientos<\/span><\/p>\n<h1><span class=\"mixed-font_heading\">Comodidad<\/span><br \/>\ncinco estrellas<\/h1>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbscroll_pos_advanced\u00bb animation_trigger_offset=\u00bb60.00,90.00&#8243; animation_end_translate_y=\u00bb-100&#8243; animation_end_opacity=\u00bb0&#8243; bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb animation_adv_start_end=\u00bbend\u00bb][vc_column_text css_animation=\u00bbfadeInUp\u00bb css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]El Hotel Parc Beaumont dispone de 75 amplias habitaciones y suites, incluidas habitaciones comunicadas dise\u00f1adas para alojar familias. Cada habitaci\u00f3n ofrece una vista relajante de los \u00e1rboles centenarios del parque o de las elegantes villas del distrito residencial de Trespoey y encarna el refinamiento. Ya sea que elija una habitaci\u00f3n con vista a la ciudad, una habitaci\u00f3n con vista al parque o una de nuestras suites, quedar\u00e1 encantado con el ambiente acogedor, la decoraci\u00f3n cuidada y el espacio generoso, propicio para el descanso y la relajaci\u00f3n.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb44&#8243; bg_position=\u00bbcustom\u00bb bg_position_x=\u00bb0&#8243; bg_position_y=\u00bb-30%\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb10%\u00bb bottom_padding=\u00bb14%\u00bb left_padding_desktop=\u00bb60&#8243; constrain_group_2=\u00bbyes\u00bb right_padding_desktop=\u00bb60&#8243; top_padding_phone=\u00bb16%\u00bb constrain_group_5=\u00bbyes\u00bb bottom_padding_phone=\u00bb16%\u00bb left_padding_phone=\u00bb18px\u00bb constrain_group_6=\u00bbyes\u00bb right_padding_phone=\u00bb18px\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbhpb_heb\u00bb disable_element=\u00bbyes\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbzoom-out-slow\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb bg_image_animation_delay=\u00bb200&#8243;][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_margin=\u00bb60px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbscroll_pos_advanced\u00bb animation_trigger_offset=\u00bb60.00,90.00&#8243; animation_end_translate_y=\u00bb-100&#8243; animation_end_opacity=\u00bb0&#8243; bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb animation_adv_start_end=\u00bbend\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb el_class=\u00bbvector_title v_alt\u00bb]<span class=\"top_line\">Alojamientos<\/span><\/p>\n<h2>Una <span class=\"mixed-font_heading\">invitacion<\/span><br \/>\nen paz<\/h2>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbscroll_pos_advanced\u00bb animation_trigger_offset=\u00bb60.00,90.00&#8243; animation_end_translate_y=\u00bb-100&#8243; animation_end_opacity=\u00bb0&#8243; bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb animation_adv_start_end=\u00bbend\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<strong>El Hotel Parc Beaumont &amp; spa<\/strong> ofrece <em>75 habitaciones y suites,<\/em> habitaciones comunicadas para familias con vistas al parque arbolado o las lujosas villas del barrio residencial \u201cTrespoey\u201d. Ya sea que elija una habitaci\u00f3n urbana, una habitaci\u00f3n tipo parque o una suite, <em>apreciar\u00e1 el espacio, la decoraci\u00f3n refinada y relajante&#8230;<\/em>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb10%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb10%\u00bb left_padding_desktop=\u00bb60&#8243; constrain_group_2=\u00bbyes\u00bb right_padding_desktop=\u00bb60&#8243; left_padding_phone=\u00bb18px\u00bb constrain_group_6=\u00bbyes\u00bb right_padding_phone=\u00bb18px\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbhpb_rooms\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][nectar_post_grid post_type=\u00bbportfolio\u00bb portfolio_category=\u00bbchambres,suites\u00bb portfolio_starting_category=\u00bball\u00bb order=\u00bbASC\u00bb orderby=\u00bbdate\u00bb stack_animation_effect=\u00bbblurred_scale\u00bb columns=\u00bb1&#8243; columns_tablet=\u00bbdefault\u00bb columns_phone=\u00bbdefault\u00bb grid_item_spacing=\u00bb40px\u00bb grid_item_height=\u00bb80vh\u00bb image_size=\u00bbfull\u00bb overlaid_aspect_ratio_image_size=\u00bbyes\u00bb overlaid_custom_image_aspect_ratio=\u00bb16-9&#8243; image_loading=\u00bbdefault\u00bb heading_tag=\u00bbh2&#8243; heading_tag_render=\u00bbdefault\u00bb font_size_max=\u00bb140px\u00bb display_categories=\u00bbyes\u00bb category_functionality=\u00bbstatic\u00bb category_style=\u00bbsee-through-button\u00bb category_display=\u00bbparent_only\u00bb additional_meta_size=\u00bbdefault\u00bb custom_fields_location=\u00bbafter_post_meta\u00bb custom_fields=\u00bb%5B%5D\u00bb grid_style=\u00bbcontent_overlaid\u00bb text_content_layout=\u00bball_middle\u00bb color_overlay=\u00bb#141414&#8243; color_overlay_opacity=\u00bb0&#8243; color_overlay_hover_opacity=\u00bb0&#8243; text_color=\u00bblight\u00bb text_color_hover=\u00bblight\u00bb text_opacity=\u00bb1&#8243; text_hover_opacity=\u00bb1&#8243; hover_effect=\u00bbslow_zoom\u00bb border_radius=\u00bb25px\u00bb posts_per_page=\u00bb5&#8243; display_type=\u00bbstack\u00bb custom_font_size=\u00bb12vw\u00bb font_size_tablet=\u00bb12vw\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_raw_js]JTNDJTIxLS0lM0NzY3JpcHQlM0VmdW5jdGlvbiUyMGhlYWRlckxvYWQlMjglMjklMjAlN0IlMEElMjAlMjB2YXIlMjBlbGVtZW50JTIwJTNEJTIwZG9jdW1lbnQuZ2V0RWxlbWVudEJ5SWQlMjglMjJoZWFkZXItb3V0ZXIlMjIlMjklM0IlMEElMjAlMjBlbGVtZW50LmNsYXNzTGlzdC5hZGQlMjglMjJhdC10b3AlMjIlMjklM0IlMEElN0QlMjAlMEF3aW5kb3cub25sb2FkJTIwJTNEJTIwaGVhZGVyTG9hZCUzQiUzQyUyRnNjcmlwdCUzRS0tJTNF[\/vc_raw_js][nectar_global_section id=\u00bb465&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb1636&#8243; bg_position=\u00bbcenter bottom\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb video_bg=\u00bbuse_video\u00bb enable_video_color_overlay=\u00bbtrue\u00bb video_overlay_color=\u00bbrgba(0,0,0,0.25)\u00bb video_mp4=\u00bbhttps:\/\/www.hotel-parc-beaumont.com\/wp-content\/uploads\/2025\/10\/VIDEO_BEAUMONT_1_MUTE_Alt_3480.mp4&#8243; video_image=\u00bb1636&#8243; background_video_loading=\u00bblazy-load\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb35%\u00bb bottom_padding=\u00bb2%\u00bb left_padding_desktop=\u00bb60&#8243; constrain_group_2=\u00bbyes\u00bb right_padding_desktop=\u00bb60&#8243; left_padding_phone=\u00bb18px\u00bb constrain_group_6=\u00bbyes\u00bb right_padding_phone=\u00bb18px\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-1291","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alojamiento - H\u00f4tel Parc Beaumont<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hotel-parc-beaumont.com\/es\/alojamiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alojamiento - H\u00f4tel Parc Beaumont\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb1636&#8243; bg_position=\u00bbcenter bottom\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb video_bg=\u00bbuse_video\u00bb enable_video_color_overlay=\u00bbtrue\u00bb video_overlay_color=\u00bbrgba(0,0,0,0.25)\u00bb video_mp4=\u00bbhttps:\/\/www.hotel-parc-beaumont.com\/wp-content\/uploads\/2025\/10\/VIDEO_BEAUMONT_1_MUTE_Alt_3480.mp4&#8243; video_image=\u00bb1636&#8243; background_video_loading=\u00bblazy-load\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb35%\u00bb bottom_padding=\u00bb2%\u00bb left_padding_desktop=\u00bb60&#8243; constrain_group_2=\u00bbyes\u00bb right_padding_desktop=\u00bb60&#8243; left_padding_phone=\u00bb18px\u00bb constrain_group_6=\u00bbyes\u00bb right_padding_phone=\u00bb18px\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hotel-parc-beaumont.com\/es\/alojamiento\/\" \/>\n<meta property=\"og:site_name\" content=\"H\u00f4tel Parc Beaumont\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hotel.parc.beaumont\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-14T09:31:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hotel-parc-beaumont.com\/wp-content\/uploads\/2025\/02\/exterieur-web--scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1784\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/es\\\/alojamiento\\\/\",\"url\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/es\\\/alojamiento\\\/\",\"name\":\"Alojamiento - H\u00f4tel Parc Beaumont\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/#website\"},\"datePublished\":\"2025-03-03T14:29:48+00:00\",\"dateModified\":\"2025-10-14T09:31:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/es\\\/alojamiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/es\\\/alojamiento\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/es\\\/alojamiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alojamiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/\",\"name\":\"H\u00f4tel Parc Beaumont\",\"description\":\"H\u00f4tel \u00e0 Pau MGallery Collection\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/#organization\",\"name\":\"H\u00f4tel Parc Beaumont\",\"url\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/HotelParcBeaumont_Logo_Green.svg\",\"contentUrl\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/HotelParcBeaumont_Logo_Green.svg\",\"width\":291,\"height\":50,\"caption\":\"H\u00f4tel Parc Beaumont\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hotel-parc-beaumont.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hotel.parc.beaumont\",\"https:\\\/\\\/www.instagram.com\\\/hotelparcbeaumont\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alojamiento - H\u00f4tel Parc Beaumont","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hotel-parc-beaumont.com\/es\/alojamiento\/","og_locale":"es_ES","og_type":"article","og_title":"Alojamiento - H\u00f4tel Parc Beaumont","og_description":"[vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb1636&#8243; bg_position=\u00bbcenter bottom\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb video_bg=\u00bbuse_video\u00bb enable_video_color_overlay=\u00bbtrue\u00bb video_overlay_color=\u00bbrgba(0,0,0,0.25)\u00bb video_mp4=\u00bbhttps:\/\/www.hotel-parc-beaumont.com\/wp-content\/uploads\/2025\/10\/VIDEO_BEAUMONT_1_MUTE_Alt_3480.mp4&#8243; video_image=\u00bb1636&#8243; background_video_loading=\u00bblazy-load\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb35%\u00bb bottom_padding=\u00bb2%\u00bb left_padding_desktop=\u00bb60&#8243; constrain_group_2=\u00bbyes\u00bb right_padding_desktop=\u00bb60&#8243; left_padding_phone=\u00bb18px\u00bb constrain_group_6=\u00bbyes\u00bb right_padding_phone=\u00bb18px\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb...","og_url":"https:\/\/www.hotel-parc-beaumont.com\/es\/alojamiento\/","og_site_name":"H\u00f4tel Parc Beaumont","article_publisher":"https:\/\/www.facebook.com\/hotel.parc.beaumont","article_modified_time":"2025-10-14T09:31:02+00:00","og_image":[{"width":2560,"height":1784,"url":"https:\/\/www.hotel-parc-beaumont.com\/wp-content\/uploads\/2025\/02\/exterieur-web--scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hotel-parc-beaumont.com\/es\/alojamiento\/","url":"https:\/\/www.hotel-parc-beaumont.com\/es\/alojamiento\/","name":"Alojamiento - H\u00f4tel Parc Beaumont","isPartOf":{"@id":"https:\/\/www.hotel-parc-beaumont.com\/#website"},"datePublished":"2025-03-03T14:29:48+00:00","dateModified":"2025-10-14T09:31:02+00:00","breadcrumb":{"@id":"https:\/\/www.hotel-parc-beaumont.com\/es\/alojamiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hotel-parc-beaumont.com\/es\/alojamiento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hotel-parc-beaumont.com\/es\/alojamiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.hotel-parc-beaumont.com\/es\/"},{"@type":"ListItem","position":2,"name":"Alojamiento"}]},{"@type":"WebSite","@id":"https:\/\/www.hotel-parc-beaumont.com\/#website","url":"https:\/\/www.hotel-parc-beaumont.com\/","name":"H\u00f4tel Parc Beaumont","description":"H\u00f4tel \u00e0 Pau MGallery Collection","publisher":{"@id":"https:\/\/www.hotel-parc-beaumont.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hotel-parc-beaumont.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.hotel-parc-beaumont.com\/#organization","name":"H\u00f4tel Parc Beaumont","url":"https:\/\/www.hotel-parc-beaumont.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hotel-parc-beaumont.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.hotel-parc-beaumont.com\/wp-content\/uploads\/2025\/02\/HotelParcBeaumont_Logo_Green.svg","contentUrl":"https:\/\/www.hotel-parc-beaumont.com\/wp-content\/uploads\/2025\/02\/HotelParcBeaumont_Logo_Green.svg","width":291,"height":50,"caption":"H\u00f4tel Parc Beaumont"},"image":{"@id":"https:\/\/www.hotel-parc-beaumont.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hotel.parc.beaumont","https:\/\/www.instagram.com\/hotelparcbeaumont\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hotel-parc-beaumont.com\/es\/wp-json\/wp\/v2\/pages\/1291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotel-parc-beaumont.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotel-parc-beaumont.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotel-parc-beaumont.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotel-parc-beaumont.com\/es\/wp-json\/wp\/v2\/comments?post=1291"}],"version-history":[{"count":5,"href":"https:\/\/www.hotel-parc-beaumont.com\/es\/wp-json\/wp\/v2\/pages\/1291\/revisions"}],"predecessor-version":[{"id":1912,"href":"https:\/\/www.hotel-parc-beaumont.com\/es\/wp-json\/wp\/v2\/pages\/1291\/revisions\/1912"}],"wp:attachment":[{"href":"https:\/\/www.hotel-parc-beaumont.com\/es\/wp-json\/wp\/v2\/media?parent=1291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}